{"id":4640,"date":"2026-01-13T12:36:34","date_gmt":"2026-01-13T11:36:34","guid":{"rendered":"https:\/\/turomas.com\/blog\/turomas-premiada-por-su-trayectoria-empresarial\/"},"modified":"2026-04-01T10:23:10","modified_gmt":"2026-04-01T08:23:10","slug":"turomas-premio-trajetoria-empresarial","status":"publish","type":"post","link":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/","title":{"rendered":"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial"},"content":{"rendered":"<p><strong>A d\u00e9cima quinta edi\u00e7\u00e3o do Pr\u00eamio Teruel Empresa aconteceu na segunda-feira, 25 de mar\u00e7o de 2019, no Sal\u00e3o de Atos da Delega\u00e7\u00e3o do Governo de Arag\u00e3o em Teruel. As quatro distin\u00e7\u00f5es, Pr\u00eamio \u00e0 Internacionaliza\u00e7\u00e3o, Pr\u00eamio \u00e0 Inova\u00e7\u00e3o, Pr\u00eamio \u00e0 Trajet\u00f3ria Empresarial e Pr\u00eamio Empresa Teruel, foram concedidas a Conservas Calanda, Aeroporto de Teruel, Turomas e MotocrossCenter, respectivamente.<\/strong><\/p>\n<p>\u00c1lvaro Tom\u00e1s, Vice-presidente da Turomas, e Antonio Ortega, Diretor Geral da empresa, receberam o pr\u00eamio das m\u00e3os de Carlos Torre, Presidente da CEOE Teruel.<\/p>\n<p>Em seu discurso, \u00c1lvaro Tom\u00e1s agradeceu o trabalho de todas as pessoas que tornaram poss\u00edvel que a Turomas se tornasse um referente mundial na fabrica\u00e7\u00e3o de m\u00e1quinas inteligentes para armazenar, carregar e cortar vidro.<\/p>\n<p>Ele tamb\u00e9m n\u00e3o deixou de mencionar seu pai, Miguel Tom\u00e1s, precursor deste projeto que come\u00e7ou h\u00e1 mais de tr\u00eas d\u00e9cadas, transformando uma paix\u00e3o em um trabalho com o qual ganharia a vida.<\/p>\n<p>Por sua vez, Antonio Ortega enfatizou a import\u00e2ncia de as Administra\u00e7\u00f5es ajudarem e incentivarem as empresas para que possam continuar crescendo, incorporar pessoal qualificado e fazer a economia da prov\u00edncia crescer. Para o crescimento econ\u00f4mico, uma cobertura de banda larga de qualidade \u00e9 relevante.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_704237821\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-para-web-3-1024x683-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-para-web-3-1024x683-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-para-web-3-1024x683-2-300x200.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-para-web-3-1024x683-2-768x512.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_704237821 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p>Antonio Ortega e \u00c1lvaro Tom\u00e1s, CEO e Vice-presidente da TUROMAS, respectivamente, junto com Carlos Torre, Presidente da CEOE Teruel, na entrega do Pr\u00eamio Empresa \u00e0 trajet\u00f3ria empresarial.<\/p>\n<p>Com este novo pr\u00eamio, a Turomas se torna a primeira empresa da prov\u00edncia premiada em todas as categorias. Em 2006, foi distinguida com o Pr\u00eamio Empresa \u00e0 Inova\u00e7\u00e3o; em 2011, com o Pr\u00eamio Empresa \u00e0 Internacionaliza\u00e7\u00e3o e, em 2014, recebeu o Pr\u00eamio Empresa Teruel.<\/p>\n<p>Al\u00e9m dos quatro reconhecimentos e como nas tr\u00eas \u00faltimas edi\u00e7\u00f5es, tamb\u00e9m foi entregue o Pr\u00eamio Semente CEOE-CEPYME, que reconhece o trabalho dos jovens empreendedores. Nesta ocasi\u00e3o, foi concedido a Agro Intelligent, um projeto focado na cria\u00e7\u00e3o e desenvolvimento de tecnologia aplicada \u00e0 Agricultura 2.0 e Ind\u00fastria 4.0, com \u00eanfase na an\u00e1lise e automa\u00e7\u00e3o.<\/p>\n<p>A inten\u00e7\u00e3o do Pr\u00eamio Empresa Teruel \u00e9 reconhecer e valorizar o alto n\u00edvel de compromisso das empresas de Teruel, independentemente de seu campo de atua\u00e7\u00e3o, por sua trajet\u00f3ria rumo \u00e0 gest\u00e3o excelente.<\/p>\n<p>As entidades organizadoras s\u00e3o o Instituto Aragon\u00eas de Fomento, as organiza\u00e7\u00f5es empresariais CEOE Teruel e CEPYME Teruel, e a C\u00e2mara de Com\u00e9rcio, Ind\u00fastria e Servi\u00e7os de Teruel.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1193541933\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-1024x683-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-1024x683-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-1024x683-2-300x200.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-1024x683-2-768x512.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1193541933 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p>Da esquerda para a direita: Ricardo J. Martinez, CEO da Agro Intelligent, vencedor do Pr\u00eamio Semente 2019. Antonio Ortega, CEO da TUROMAS, e \u00c1lvaro Tom\u00e1s, Vice-presidente da TUROMAS, vencedores do Pr\u00eamio Empresa \u00e0 trajet\u00f3ria empresarial. Alejandro Ibrahim, CEO do Aeroporto de Teruel-Plata, vencedor do Pr\u00eamio Empresa \u00e0 Inova\u00e7\u00e3o. Iv\u00e1n Segura, Diretor do Motocross Centre, vencedor do Pr\u00eamio Empresa 2019. Ismael Conesa, CEO da Conservas Calanda, vencedor do Pr\u00eamio Empresa \u00e0 Internacionaliza\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A d\u00e9cima quinta edi\u00e7\u00e3o do Pr\u00eamio Teruel Empresa aconteceu na segunda-feira, 25 de mar\u00e7o de 2019, no Sal\u00e3o de Atos da Delega\u00e7\u00e3o do Governo de Arag\u00e3o em Teruel. As quatro distin\u00e7\u00f5es, Pr\u00eamio \u00e0 Internacionaliza\u00e7\u00e3o, Pr\u00eamio \u00e0 Inova\u00e7\u00e3o, Pr\u00eamio \u00e0 Trajet\u00f3ria Empresarial e Pr\u00eamio Empresa Teruel, foram concedidas a Conservas Calanda, Aeroporto de Teruel, Turomas e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3,4],"tags":[],"class_list":["post-4640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turomas-in-the-world","category-turomas-news","category-turomas-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A TUROMAS foi premiada por sua trajet\u00f3ria empresarial | Turomas PT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial | Turomas PT\" \/>\n<meta property=\"og:description\" content=\"A d\u00e9cima quinta edi\u00e7\u00e3o do Pr\u00eamio Teruel Empresa aconteceu na segunda-feira, 25 de mar\u00e7o de 2019, no Sal\u00e3o de Atos da Delega\u00e7\u00e3o do Governo de Arag\u00e3o em Teruel. As quatro distin\u00e7\u00f5es, Pr\u00eamio \u00e0 Internacionaliza\u00e7\u00e3o, Pr\u00eamio \u00e0 Inova\u00e7\u00e3o, Pr\u00eamio \u00e0 Trajet\u00f3ria Empresarial e Pr\u00eamio Empresa Teruel, foram concedidas a Conservas Calanda, Aeroporto de Teruel, Turomas e...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/\" \/>\n<meta property=\"og:site_name\" content=\"Turomas PT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turomas.machinery\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T11:36:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T08:23:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-768x512-1-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"turomas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@turomas\" \/>\n<meta name=\"twitter:site\" content=\"@turomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"turomas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/\"},\"author\":{\"name\":\"turomas_admin\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"headline\":\"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial\",\"datePublished\":\"2026-01-13T11:36:34+00:00\",\"dateModified\":\"2026-04-01T08:23:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/\"},\"wordCount\":520,\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Foto-premiados-Premio-Empresa-768x512-1-3.webp\",\"articleSection\":[\"TUROMAS IN THE WORLD\",\"TUROMAS NEWS\",\"TUROMAS TECHNOLOGY\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/\",\"name\":\"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial | Turomas PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Foto-premiados-Premio-Empresa-768x512-1-3.webp\",\"datePublished\":\"2026-01-13T11:36:34+00:00\",\"dateModified\":\"2026-04-01T08:23:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Foto-premiados-Premio-Empresa-768x512-1-3.webp\",\"contentUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Foto-premiados-Premio-Empresa-768x512-1-3.webp\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-premio-trajetoria-empresarial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\",\"name\":\"Turomas PT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turomas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\",\"name\":\"turomas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"caption\":\"turomas_admin\"},\"sameAs\":[\"https:\\\/\\\/turomas.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial | Turomas PT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/","og_locale":"pt_PT","og_type":"article","og_title":"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial | Turomas PT","og_description":"A d\u00e9cima quinta edi\u00e7\u00e3o do Pr\u00eamio Teruel Empresa aconteceu na segunda-feira, 25 de mar\u00e7o de 2019, no Sal\u00e3o de Atos da Delega\u00e7\u00e3o do Governo de Arag\u00e3o em Teruel. As quatro distin\u00e7\u00f5es, Pr\u00eamio \u00e0 Internacionaliza\u00e7\u00e3o, Pr\u00eamio \u00e0 Inova\u00e7\u00e3o, Pr\u00eamio \u00e0 Trajet\u00f3ria Empresarial e Pr\u00eamio Empresa Teruel, foram concedidas a Conservas Calanda, Aeroporto de Teruel, Turomas e...","og_url":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/","og_site_name":"Turomas PT","article_publisher":"https:\/\/www.facebook.com\/turomas.machinery","article_published_time":"2026-01-13T11:36:34+00:00","article_modified_time":"2026-04-01T08:23:10+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-768x512-1-3.webp","type":"image\/webp"}],"author":"turomas_admin","twitter_card":"summary_large_image","twitter_creator":"@turomas","twitter_site":"@turomas","twitter_misc":{"Escrito por":"turomas_admin","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/#article","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/"},"author":{"name":"turomas_admin","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"headline":"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial","datePublished":"2026-01-13T11:36:34+00:00","dateModified":"2026-04-01T08:23:10+00:00","mainEntityOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/"},"wordCount":520,"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-768x512-1-3.webp","articleSection":["TUROMAS IN THE WORLD","TUROMAS NEWS","TUROMAS TECHNOLOGY"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/","url":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/","name":"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial | Turomas PT","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/#primaryimage"},"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-768x512-1-3.webp","datePublished":"2026-01-13T11:36:34+00:00","dateModified":"2026-04-01T08:23:10+00:00","author":{"@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"breadcrumb":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/#primaryimage","url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-768x512-1-3.webp","contentUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-premiados-Premio-Empresa-768x512-1-3.webp","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-premio-trajetoria-empresarial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turomas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"A TUROMAS foi premiada por sua trajet\u00f3ria empresarial"}]},{"@type":"WebSite","@id":"https:\/\/turomas.com\/pt\/#website","url":"https:\/\/turomas.com\/pt\/","name":"Turomas PT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turomas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315","name":"turomas_admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","caption":"turomas_admin"},"sameAs":["https:\/\/turomas.com"]}]}},"_links":{"self":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/comments?post=4640"}],"version-history":[{"count":3,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4640\/revisions"}],"predecessor-version":[{"id":6169,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4640\/revisions\/6169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media\/5098"}],"wp:attachment":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media?parent=4640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/categories?post=4640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/tags?post=4640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}