{"id":4644,"date":"2026-01-13T12:36:34","date_gmt":"2026-01-13T11:36:34","guid":{"rendered":"https:\/\/turomas.com\/blog\/turomas-supera-sus-expectativas-en-china-glass-2019\/"},"modified":"2026-04-01T10:10:38","modified_gmt":"2026-04-01T08:10:38","slug":"turomas-supera-expectativas-na-china-glass-2019","status":"publish","type":"post","link":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/","title":{"rendered":"Turomas supera expectativas na China Glass 2019"},"content":{"rendered":"<p style=\"text-align: left;\"><strong>A Exposi\u00e7\u00e3o T\u00e9cnica Internacional do Vidro Industrial da China, mais conhecida como China Glass, \u00e9 a maior feira profissional de vidro da \u00c1sia e uma das duas mais importantes do setor mundialmente. Esta exposi\u00e7\u00e3o anual \u00e9 organizada pela Sociedade de Cer\u00e2mica da China todas as primaveras.<\/strong><\/p>\n<p>Cerca de 1.000 expositores de 30 pa\u00edses e estados asi\u00e1ticos, europeus e americanos participaram da trig\u00e9sima edi\u00e7\u00e3o da China Glass de 22 a 25 de maio. Como nas edi\u00e7\u00f5es anteriores, o evento aconteceu nos pavilh\u00f5es do New China International Exhibition Center (NCIEC), em Pequim.<\/p>\n<p>Assim como outros grandes fabricantes nacionais e internacionais de m\u00e1quinas, a Turomas n\u00e3o quis perder a oportunidade de mostrar seus avan\u00e7os e progressos neste evento de refer\u00eancia. Para a capital do pa\u00eds asi\u00e1tico viajaram o Vice-Presidente da Turomas, \u00c1lvaro Tom\u00e1s, e parte da equipe comercial representada por Ruth Ruiz, Guillermo Ortega e Eduardo Nieto.<\/p>\n<p>A presen\u00e7a da Turomas na trig\u00e9sima edi\u00e7\u00e3o da China Glass superou as expectativas, com um aumento de 20% no n\u00famero de visitas no primeiro dia em compara\u00e7\u00e3o com a edi\u00e7\u00e3o de 2015. As visitas resultaram no fechamento de acordos importantes e na expans\u00e3o do interesse pela maquinaria da Turomas at\u00e9 a \u00cdndia, um mercado onde se prev\u00ea um alto volume de vendas no futuro.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_551212199\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/CHINA-2019-1-1024x768-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/CHINA-2019-1-1024x768-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/CHINA-2019-1-1024x768-2-300x225.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/CHINA-2019-1-1024x768-2-768x576.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_551212199 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p style=\"text-align: left;\">\u201cDe acordo com nossa estrat\u00e9gia de fortalecer a posi\u00e7\u00e3o nos mercados asi\u00e1ticos e refor\u00e7ar nossas rela\u00e7\u00f5es comerciais com nossa nova rede de distribui\u00e7\u00e3o em pa\u00edses como a regi\u00e3o MENA, \u00cdndia, Vietn\u00e3, Jap\u00e3o, Filipinas, Coreia e Austr\u00e1lia, \u00e9 imprescind\u00edvel nossa presen\u00e7a nesta feira. Ela \u00e9 a principal feira da regi\u00e3o do Oriente M\u00e9dio at\u00e9 a Oceania e, globalmente, a segunda mais importante depois da Glasstec\u201d, declara \u00c1lvaro Tom\u00e1s.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_195686385\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"765\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/CHINA-2019-2-1024x768-2.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/CHINA-2019-2-1024x768-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/CHINA-2019-2-1024x768-2-300x225.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/CHINA-2019-2-1024x768-2-768x576.webp 768w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_195686385 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p>O estande da Turomas atraiu a aten\u00e7\u00e3o de clientes potenciais, mas tamb\u00e9m foi um ponto de encontro com alguns de seus clientes atuais, que vieram da Espanha, Portugal e outros pa\u00edses europeus e sul-americanos, que n\u00e3o quiseram deixar de cumprimentar e trocar impress\u00f5es.<\/p>\n<p>Sem d\u00favida, devido aos excelentes resultados em termos de visibilidade e grandes oportunidades de neg\u00f3cios, a China Glass se torna um evento anual obrigat\u00f3rio para a Turomas.<\/p>\n<p>Paralelamente \u00e0 exposi\u00e7\u00e3o e aos encontros comerciais, ocorreram semin\u00e1rios t\u00e9cnicos abordando temas relacionados \u00e0s novidades, tend\u00eancias e evolu\u00e7\u00e3o do setor. Assuntos como fabrica\u00e7\u00e3o inteligente, solu\u00e7\u00f5es, aplica\u00e7\u00f5es, decora\u00e7\u00e3o, economia de energia e respeito ao meio ambiente, entre outros.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_392612430\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"704\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/IMG_4472-1024x707-2.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/IMG_4472-1024x707-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/IMG_4472-1024x707-2-300x207.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/IMG_4472-1024x707-2-768x530.webp 768w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_392612430 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h2>Cena com sabor mediterr\u00e2neo<\/h2>\n<p>Na quinta-feira, 23 de maio, a Turomas convidou seus clientes e distribuidores para um jantar. O local escolhido para o encontro foi o terra\u00e7o do moderno restaurante Migas Mercado, localizado em uma cobertura no cora\u00e7\u00e3o de Pequim, onde s\u00e3o servidos pratos mediterr\u00e2neos de alta qualidade.<\/p>\n<p>Durante mais de tr\u00eas horas, os participantes puderam desfrutar de um espa\u00e7o confort\u00e1vel para conversar e continuar se conectando fora do recinto da feira, al\u00e9m de apreciar as fant\u00e1sticas vistas dos monumentos mais emblem\u00e1ticos de Pequim.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Exposi\u00e7\u00e3o T\u00e9cnica Internacional do Vidro Industrial da China, mais conhecida como China Glass, \u00e9 a maior feira profissional de vidro da \u00c1sia e uma das duas mais importantes do setor mundialmente. Esta exposi\u00e7\u00e3o anual \u00e9 organizada pela Sociedade de Cer\u00e2mica da China todas as primaveras. Cerca de 1.000 expositores de 30 pa\u00edses e estados&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3,4],"tags":[],"class_list":["post-4644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turomas-in-the-world","category-turomas-news","category-turomas-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Turomas supera expectativas na China Glass 2019 | Turomas PT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turomas supera expectativas na China Glass 2019 | Turomas PT\" \/>\n<meta property=\"og:description\" content=\"A Exposi\u00e7\u00e3o T\u00e9cnica Internacional do Vidro Industrial da China, mais conhecida como China Glass, \u00e9 a maior feira profissional de vidro da \u00c1sia e uma das duas mais importantes do setor mundialmente. Esta exposi\u00e7\u00e3o anual \u00e9 organizada pela Sociedade de Cer\u00e2mica da China todas as primaveras. Cerca de 1.000 expositores de 30 pa\u00edses e estados...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Turomas PT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turomas.machinery\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T11:36:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T08:10:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-entrada-China-Glass-768x576-1-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"turomas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@turomas\" \/>\n<meta name=\"twitter:site\" content=\"@turomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"turomas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/\"},\"author\":{\"name\":\"turomas_admin\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"headline\":\"Turomas supera expectativas na China Glass 2019\",\"datePublished\":\"2026-01-13T11:36:34+00:00\",\"dateModified\":\"2026-04-01T08:10:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/\"},\"wordCount\":540,\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Foto-entrada-China-Glass-768x576-1-3.webp\",\"articleSection\":[\"TUROMAS IN THE WORLD\",\"TUROMAS NEWS\",\"TUROMAS TECHNOLOGY\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/\",\"name\":\"Turomas supera expectativas na China Glass 2019 | Turomas PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Foto-entrada-China-Glass-768x576-1-3.webp\",\"datePublished\":\"2026-01-13T11:36:34+00:00\",\"dateModified\":\"2026-04-01T08:10:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Foto-entrada-China-Glass-768x576-1-3.webp\",\"contentUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Foto-entrada-China-Glass-768x576-1-3.webp\",\"width\":768,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-supera-expectativas-na-china-glass-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turomas supera expectativas na China Glass 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\",\"name\":\"Turomas PT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turomas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\",\"name\":\"turomas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"caption\":\"turomas_admin\"},\"sameAs\":[\"https:\\\/\\\/turomas.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Turomas supera expectativas na China Glass 2019 | Turomas PT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/","og_locale":"pt_PT","og_type":"article","og_title":"Turomas supera expectativas na China Glass 2019 | Turomas PT","og_description":"A Exposi\u00e7\u00e3o T\u00e9cnica Internacional do Vidro Industrial da China, mais conhecida como China Glass, \u00e9 a maior feira profissional de vidro da \u00c1sia e uma das duas mais importantes do setor mundialmente. Esta exposi\u00e7\u00e3o anual \u00e9 organizada pela Sociedade de Cer\u00e2mica da China todas as primaveras. Cerca de 1.000 expositores de 30 pa\u00edses e estados...","og_url":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/","og_site_name":"Turomas PT","article_publisher":"https:\/\/www.facebook.com\/turomas.machinery","article_published_time":"2026-01-13T11:36:34+00:00","article_modified_time":"2026-04-01T08:10:38+00:00","og_image":[{"width":768,"height":576,"url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-entrada-China-Glass-768x576-1-3.webp","type":"image\/webp"}],"author":"turomas_admin","twitter_card":"summary_large_image","twitter_creator":"@turomas","twitter_site":"@turomas","twitter_misc":{"Escrito por":"turomas_admin","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/#article","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/"},"author":{"name":"turomas_admin","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"headline":"Turomas supera expectativas na China Glass 2019","datePublished":"2026-01-13T11:36:34+00:00","dateModified":"2026-04-01T08:10:38+00:00","mainEntityOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/"},"wordCount":540,"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-entrada-China-Glass-768x576-1-3.webp","articleSection":["TUROMAS IN THE WORLD","TUROMAS NEWS","TUROMAS TECHNOLOGY"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/","url":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/","name":"Turomas supera expectativas na China Glass 2019 | Turomas PT","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/#primaryimage"},"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-entrada-China-Glass-768x576-1-3.webp","datePublished":"2026-01-13T11:36:34+00:00","dateModified":"2026-04-01T08:10:38+00:00","author":{"@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"breadcrumb":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/#primaryimage","url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-entrada-China-Glass-768x576-1-3.webp","contentUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Foto-entrada-China-Glass-768x576-1-3.webp","width":768,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-supera-expectativas-na-china-glass-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turomas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Turomas supera expectativas na China Glass 2019"}]},{"@type":"WebSite","@id":"https:\/\/turomas.com\/pt\/#website","url":"https:\/\/turomas.com\/pt\/","name":"Turomas PT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turomas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315","name":"turomas_admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","caption":"turomas_admin"},"sameAs":["https:\/\/turomas.com"]}]}},"_links":{"self":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/comments?post=4644"}],"version-history":[{"count":3,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4644\/revisions"}],"predecessor-version":[{"id":6156,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4644\/revisions\/6156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media\/5092"}],"wp:attachment":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media?parent=4644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/categories?post=4644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/tags?post=4644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}