{"id":4654,"date":"2026-01-13T12:36:37","date_gmt":"2026-01-13T11:36:37","guid":{"rendered":"https:\/\/turomas.com\/blog\/turomasintheworld-turomas-en-mejico\/"},"modified":"2026-04-01T11:21:13","modified_gmt":"2026-04-01T09:21:13","slug":"turomasintheworld-turomas-no-mexico","status":"publish","type":"post","link":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/","title":{"rendered":"TuromasInTheWorld: Turomas no M\u00e9xico"},"content":{"rendered":"<p style=\"text-align: left;\"><strong>Glasser, Correlli Glass e Inova Glass s\u00e3o tr\u00eas empresas mexicanas com uma longa trajet\u00f3ria na ind\u00fastria do vidro. Al\u00e9m da origem e do extenso percurso, duas coisas mais elas t\u00eam em comum: o trabalho em equipe e a aposta nas solu\u00e7\u00f5es de maquinaria inteligente da TUROMAS.<\/strong><\/p>\n<h2>Glasser<\/h2>\n<p>\u201cParece-nos uma m\u00e1quina pr\u00e1tica, pensada nas necessidades do cliente, n\u00e3o nas necessidades do fabricante de maquinaria, e tem nos dado resultados muito bons.\u201d<\/p>\n<p><strong>Jorge G\u00fazman<\/strong><\/p>\n<p>PRESIDENTE DA GLASSER<\/p>\n<p><a style=\"background-color: #ffffff;\" href=\"http:\/\/www.glasser.com.mx\/\" target=\"_blank\" rel=\"noopener noreferrer\">Glasser<\/a>, como \u00e9 conhecida hoje, nasceu h\u00e1 30 anos. Antes, foi precedida pela Vitrocolor e, muito antes disso, por outras empresas. O sobrenome Guzm\u00e1n est\u00e1 presente na ind\u00fastria do vidro desde 1931. Jorge Guzm\u00e1n, o atual presidente do grupo empresarial Glasser, representa a terceira gera\u00e7\u00e3o do neg\u00f3cio familiar.<\/p>\n<p>Ap\u00f3s se dedicar ao vidro fundido e ao vidro soprado, agora processa vidro plano e \u00e9 especializada em vidro para eletrodom\u00e9sticos. Com suas tr\u00eas f\u00e1bricas localizadas na Cidade do M\u00e9xico, Quer\u00e9taro e Santiago do Chile, a empresa vende para a Am\u00e9rica do Sul e os Estados Unidos.<\/p>\n<p>O principal objetivo do grupo mexicano \u00e9 oferecer um bom atendimento ao cliente. Um cliente que, a cada dia, exige mais qualidade e precis\u00e3o no produto, no processo de t\u00eampera, nas cores, no acabamento\u2026 Uma exig\u00eancia que levou \u00e0 automa\u00e7\u00e3o dos processos. E \u00e9 a\u00ed que entra a tecnologia avan\u00e7ada da TUROMAS.<\/p>\n<p>A primeira vez que a Glasser e a TUROMAS se encontraram foi na 24\u00aa edi\u00e7\u00e3o da Glasstec, a principal feira mundial da ind\u00fastria do vidro, realizada em D\u00fcsseldorf (Alemanha) em 2016. O que chamou especialmente a aten\u00e7\u00e3o foi a configura\u00e7\u00e3o e o desempenho da mesa de corte, caracter\u00edsticas t\u00e9cnicas que n\u00e3o haviam encontrado em outras marcas europeias.<\/p>\n<p>Al\u00e9m disso, \u201cpareceu-nos uma m\u00e1quina pr\u00e1tica, pensada nas necessidades do cliente, n\u00e3o nas necessidades do fabricante de maquinaria, e tem nos dado resultados muito bons\u201d, afirma Jorge.<\/p>\n<p>A mesa de corte de vidro monol\u00edtico instalada na f\u00e1brica de Quer\u00e9taro \u00e9 o modelo <a href=\"https:\/\/www.turomas.com\/maquinaria\/corte-vidrio-monolitico\/rubi-500-series\/\" target=\"_blank\" rel=\"noopener noreferrer\">RUBI 513VAC<\/a> e trabalha em conjunto com uma mesa de tronzagem <a href=\"https:\/\/www.turomas.com\/maquinaria\/mesas-carga-tronzado\/mesas-de-tronzado\/\" target=\"_blank\" rel=\"noopener noreferrer\">MT 300<\/a>. Esta mesa \u00e9 capaz de alimentar tr\u00eas linhas cont\u00ednuas de alta produ\u00e7\u00e3o e tem permitido fabricar at\u00e9 um milh\u00e3o de pe\u00e7as por m\u00eas.<\/p>\n<p>Al\u00e9m do aumento na produ\u00e7\u00e3o, a m\u00e1quina resolveu v\u00e1rios problemas que a empresa enfrentava, como \u201ca carga do vidro na mesa de corte, o posicionamento a ponto zero, a rapidez e a precis\u00e3o no corte, e a velocidade no deslocamento das chapas para a coloca\u00e7\u00e3o da pr\u00f3xima folha de vidro\u201d, lista Jorge.<\/p>\n<p>O crescimento n\u00e3o veio apenas da m\u00e3o das novas tecnologias que ajudam a melhorar o trabalho, mas tamb\u00e9m do fator humano, que sempre foi fundamental. <strong>\u201cGostamos de trabalhar em equipe; gostamos de formar equipes criativas e colaborativas\u201d<\/strong>, reconhece o presidente. <strong>\u201cA Glasser somos todos\u201d<\/strong>, esse \u00e9 o seu lema.<\/p>\n<h3>Correlli Glass<\/h3>\n<p>\u201c\u00c9 importante contar com uma marca s\u00f3lida como a TUROMAS, pois, se queremos ser os melhores, devemos estar com as melhores marcas.\u201d<\/p>\n<p><strong>C\u00e9sar Castellanos<\/strong><\/p>\n<p>PRESIDENTE DA CORRELLI GLASS<\/p>\n<p>Em 1991, C\u00e9sar Castellanos e Silvia S\u00e1nchez, marido e mulher, fundaram <a href=\"http:\/\/correlliglass.com.mx\/\" target=\"_blank\" rel=\"noopener noreferrer\">Correlli Glass<\/a>. Naquela \u00e9poca, todos os processos do vidro eram manuais, dentro de jornadas de trabalho que sabiam quando come\u00e7avam, mas n\u00e3o quando terminavam.<\/p>\n<p>O fato de come\u00e7arem o neg\u00f3cio do zero e realizarem o trabalho manualmente os surpreendeu quando conheceram as mesas de corte da TUROMAS pela primeira vez. A fabrica\u00e7\u00e3o meticulosa e robustez das m\u00e1quinas transmitiu-lhes seguran\u00e7a para cortar grandes folhas de vidro.<\/p>\n<p>O casal de empres\u00e1rios mexicanos j\u00e1 havia experimentado outras marcas, mas desde que encontraram a TUROMAS, ficaram \u201cencantados com a forma como se adaptaram \u00e0s nossas necessidades e n\u00e3o n\u00f3s \u00e0s suas linhas j\u00e1 estabelecidas\u201d, afirma C\u00e9sar.<\/p>\n<p>Comparado a outros fabricantes, tamb\u00e9m ficaram impressionados com a velocidade e a precis\u00e3o no corte do vidro. Al\u00e9m disso, reconhecem que o sistema de carga da TUROMAS, para levantar e manipular as folhas de vidro, ajudou a melhorar a qualidade e a efici\u00eancia dos seus processos. A combina\u00e7\u00e3o que a Correlli Glass escolheu foi a mesa de corte de vidro monol\u00edtico <a href=\"https:\/\/www.turomas.com\/maquinaria\/corte-vidrio-monolitico\/rubi-400-series\/\" target=\"_blank\" rel=\"noopener noreferrer\">RUBI 403VAC<\/a>-6 e a mesa de tronzagem <a href=\"https:\/\/www.turomas.com\/maquinaria\/mesas-carga-tronzado\/mesas-de-tronzado\/\" target=\"_blank\" rel=\"noopener noreferrer\">MT 300<\/a>.<\/p>\n<p>Al\u00e9m disso, o trin\u00f4mio efici\u00eancia, qualidade e precis\u00e3o \u00e9 fundamental para os vidros de camada, cuja instala\u00e7\u00e3o \u00e9 uma tend\u00eancia arquitet\u00f4nica nas fachadas e janelas, segundo o diretor.<\/p>\n<p>Com quase tr\u00eas d\u00e9cadas de trajet\u00f3ria, h\u00e1 dez anos, entraram no vidro temperado. Hoje, a Correlli Glass possui o maior n\u00famero de fornos de t\u00eampera da Cidade do M\u00e9xico. A quantidade e a qualidade os diferencia do restante, pois atendem 24 horas por dia. De fato, foram pioneiros ao atender rapidamente os clientes a qualquer hora, de dia ou de noite.<\/p>\n<p>No setor de m\u00f3veis, decora\u00e7\u00e3o, autom\u00f3veis e arquitetura, a empresa mexicana est\u00e1 bem posicionada. Entre alguns dos seus clientes mais importantes est\u00e3o Saint-Gobain e os grupos hoteleiros Posadas e Quinta Real. Todos os meses, trabalham no envidra\u00e7amento e decora\u00e7\u00e3o de um hotel da \u00faltima rede mencionada.<\/p>\n<p>O metrobus de Pachuca, o Centro de Exposi\u00e7\u00f5es do M\u00e9xico e v\u00e1rios dos museus mais importantes do pa\u00eds est\u00e3o entre os projetos mais emblem\u00e1ticos da Correlli Glass. Em breve, t\u00eam novos e interessantes projetos em Monterrey e \u201c\u00e9 importante contar com uma marca s\u00f3lida como a TUROMAS\u201d, pois \u201cse queremos ser os melhores, devemos estar com as melhores marcas\u201d, afirma C\u00e9sar.<\/p>\n<p>Embora o segredo do sucesso da empresa n\u00e3o fosse poss\u00edvel sem as pessoas. \u201cAdoro trabalhar os valores com toda a minha equipe, acredito que isso \u00e9 a base do sucesso de qualquer empresa de qualquer ramo\u201d, reconhece Silvia, que, com humor e carinho, chama de \u201cfilhos\u201d os quase duzentos funcion\u00e1rios das plantas da Cidade do M\u00e9xico e Monterrey.<\/p>\n<h4>Inova Glass<\/h4>\n<p>\u201cAs linhas de corte e o armaz\u00e9m inteligente que adquirimos s\u00e3o os mais avan\u00e7ados tecnologicamente, com decapagem, aspiradores, etiquetadoras, motores lineares&#8230; e isso nos ajudou muito.\u201d<\/p>\n<p><strong>Gustavo Moreno<\/strong><\/p>\n<p>DIRETOR DA INOVA GLASS<\/p>\n<p>A Inova Glass foi fundada em 2007. Come\u00e7ou na ind\u00fastria com um forno r\u00fastico, fabricado manualmente. Ao longo destes 12 anos, cresceu e hoje possui plantas em Chihuahua, Hermosillo, Torre\u00f3n, Mazatl\u00e1n e Aguascalientes.<\/p>\n<p>As plantas de Hermosillo, Mazatl\u00e1n e Aguascalientes t\u00eam nomes pr\u00f3prios: Termiglass, Cristal Temperado de Mazatl\u00e1n e Magnoglass, respetivamente. Quanto ao vidro, trabalham com vidro temperado plano, temperado curvo, laminado certificado, insulado e pintado (com pintura cer\u00e2mica ou pintura a frio).<\/p>\n<p>O grupo Inova Glass tem evolu\u00eddo para a automa\u00e7\u00e3o e simplifica\u00e7\u00e3o dos processos e, durante essa transforma\u00e7\u00e3o, encontrou a solu\u00e7\u00e3o inteligente da TUROMAS para automatizar o processo industrial.<\/p>\n<p>O investimento na automa\u00e7\u00e3o, embora tenha trazido maior produtividade e efici\u00eancia, foi motivado por um tr\u00e1gico acidente de trabalho na f\u00e1brica de Chihuahua. Um evento que fez com que a seguran\u00e7a e a integridade f\u00edsica dos funcion\u00e1rios se tornassem a prioridade n\u00famero um.<\/p>\n<p>Gustavo Moreno, \u00e0 frente do grupo de empresas mexicanas, est\u00e1 muito satisfeito com a rela\u00e7\u00e3o com a TUROMAS. Profissional e excelente s\u00e3o os adjetivos que ele usa para qualificar o trabalho e o suporte t\u00e9cnico da marca espanhola.<\/p>\n<p>Em 2014, comprou o seu primeiro armaz\u00e9m inteligente, tornando-se na primeira empresa mexicana a contar com um carregador autom\u00e1tico capaz de gerir completamente o armazenamento e transporte do vidro. Hoje, j\u00e1 possui tr\u00eas e est\u00e1 em conversa\u00e7\u00f5es com a TUROMAS para adquirir o quarto.<\/p>\n<p>Al\u00e9m do trio de armaz\u00e9ns inteligentes, apostou em tr\u00eas mesas de corte de vidro monol\u00edtico e uma para corte de vidro laminado. \u201cAs linhas de corte e o armaz\u00e9m inteligente que adquirimos s\u00e3o os mais avan\u00e7ados tecnologicamente, com decapagem, aspiradores, etiquetadoras, motores lineares\u2026 e isso nos ajudou muito\u201d, afirma Gustavo.<\/p>\n<p>\u201cEstamos muito convencidos de que a TUROMAS \u00e9 uma das melhores marcas, sen\u00e3o a melhor, a n\u00edvel mundial em linhas de corte e armaz\u00e9ns inteligentes\u201d, reflete um gerente sempre atento \u00e0s mudan\u00e7as do mercado, disposto a inovar, melhorar e prosperar.<\/p>\n<h5>Entrevista com Jorge, C\u00e9sar e Gustavo<\/h5>\n\n<p><iframe loading=\"lazy\" class=\"elementor-video\" frameborder=\"0\" allowfullscreen=\"\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" title=\"TUROMAS in the World: Mexico - Glasser, Correlliglass &amp; Inova\" width=\"100%\" height=\"500\" src=\"https:\/\/www.youtube.com\/embed\/KV-47GVVCag?controls=1&amp;rel=0&amp;playsinline=0&amp;cc_load_policy=0&amp;autoplay=0&amp;enablejsapi=1&amp;origin=https%3A%2F%2Fwww.turomas.com&amp;widgetid=1&amp;forigin=https%3A%2F%2Fwww.turomas.com%2Fturomasintheworld-turomas-en-mejico%2F&amp;aoriginsup=1&amp;gporigin=https%3A%2F%2Fwww.turomas.com%2Fnoticias%2F&amp;vf=6\" id=\"widget2\" data-gtm-yt-inspected-9=\"true\"><\/iframe><br \/>\n\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de su larga trayectoria en la industria vidriera, Glasser, Correlli Glass e Inova Glass tienen dos cosas en com\u00fan: el trabajo en equipo y la apuesta por la maquinaria inteligente de TUROMAS.<\/p>\n","protected":false},"author":1,"featured_media":5058,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3,4],"tags":[],"class_list":["post-4654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turomas-in-the-world","category-turomas-news","category-turomas-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TuromasInTheWorld: Turomas no M\u00e9xico | Turomas PT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TuromasInTheWorld: Turomas no M\u00e9xico | Turomas PT\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s de su larga trayectoria en la industria vidriera, Glasser, Correlli Glass e Inova Glass tienen dos cosas en com\u00fan: el trabajo en equipo y la apuesta por la maquinaria inteligente de TUROMAS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Turomas PT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turomas.machinery\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T11:36:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T09:21:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/PORTADA-Tiny-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2041\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"turomas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@turomas\" \/>\n<meta name=\"twitter:site\" content=\"@turomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"turomas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/\"},\"author\":{\"name\":\"turomas_admin\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"headline\":\"TuromasInTheWorld: Turomas no M\u00e9xico\",\"datePublished\":\"2026-01-13T11:36:37+00:00\",\"dateModified\":\"2026-04-01T09:21:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/\"},\"wordCount\":1421,\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/PORTADA-Tiny-3.webp\",\"articleSection\":[\"TUROMAS IN THE WORLD\",\"TUROMAS NEWS\",\"TUROMAS TECHNOLOGY\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/\",\"name\":\"TuromasInTheWorld: Turomas no M\u00e9xico | Turomas PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/PORTADA-Tiny-3.webp\",\"datePublished\":\"2026-01-13T11:36:37+00:00\",\"dateModified\":\"2026-04-01T09:21:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/PORTADA-Tiny-3.webp\",\"contentUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/PORTADA-Tiny-3.webp\",\"width\":2041,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomasintheworld-turomas-no-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TuromasInTheWorld: Turomas no M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\",\"name\":\"Turomas PT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turomas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\",\"name\":\"turomas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"caption\":\"turomas_admin\"},\"sameAs\":[\"https:\\\/\\\/turomas.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TuromasInTheWorld: Turomas no M\u00e9xico | Turomas PT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/","og_locale":"pt_PT","og_type":"article","og_title":"TuromasInTheWorld: Turomas no M\u00e9xico | Turomas PT","og_description":"Adem\u00e1s de su larga trayectoria en la industria vidriera, Glasser, Correlli Glass e Inova Glass tienen dos cosas en com\u00fan: el trabajo en equipo y la apuesta por la maquinaria inteligente de TUROMAS.","og_url":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/","og_site_name":"Turomas PT","article_publisher":"https:\/\/www.facebook.com\/turomas.machinery","article_published_time":"2026-01-13T11:36:37+00:00","article_modified_time":"2026-04-01T09:21:13+00:00","og_image":[{"width":2041,"height":1200,"url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/PORTADA-Tiny-3.webp","type":"image\/webp"}],"author":"turomas_admin","twitter_card":"summary_large_image","twitter_creator":"@turomas","twitter_site":"@turomas","twitter_misc":{"Escrito por":"turomas_admin","Tempo estimado de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/#article","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/"},"author":{"name":"turomas_admin","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"headline":"TuromasInTheWorld: Turomas no M\u00e9xico","datePublished":"2026-01-13T11:36:37+00:00","dateModified":"2026-04-01T09:21:13+00:00","mainEntityOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/"},"wordCount":1421,"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/PORTADA-Tiny-3.webp","articleSection":["TUROMAS IN THE WORLD","TUROMAS NEWS","TUROMAS TECHNOLOGY"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/","url":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/","name":"TuromasInTheWorld: Turomas no M\u00e9xico | Turomas PT","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/#primaryimage"},"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/PORTADA-Tiny-3.webp","datePublished":"2026-01-13T11:36:37+00:00","dateModified":"2026-04-01T09:21:13+00:00","author":{"@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"breadcrumb":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/#primaryimage","url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/PORTADA-Tiny-3.webp","contentUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/PORTADA-Tiny-3.webp","width":2041,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/turomas.com\/pt\/blog\/turomasintheworld-turomas-no-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turomas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"TuromasInTheWorld: Turomas no M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/turomas.com\/pt\/#website","url":"https:\/\/turomas.com\/pt\/","name":"Turomas PT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turomas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315","name":"turomas_admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","caption":"turomas_admin"},"sameAs":["https:\/\/turomas.com"]}]}},"_links":{"self":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/comments?post=4654"}],"version-history":[{"count":3,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4654\/revisions"}],"predecessor-version":[{"id":6212,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4654\/revisions\/6212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media\/5058"}],"wp:attachment":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media?parent=4654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/categories?post=4654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/tags?post=4654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}