{"id":4668,"date":"2026-01-13T12:36:40","date_gmt":"2026-01-13T11:36:40","guid":{"rendered":"https:\/\/turomas.com\/blog\/semanas-inhouse-turomas-abre-sus-puertas-de-forma-exclusiva-segura-y-personalizada\/"},"modified":"2026-04-01T11:40:07","modified_gmt":"2026-04-01T09:40:07","slug":"semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada","status":"publish","type":"post","link":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/","title":{"rendered":"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada"},"content":{"rendered":"<p>Se h\u00e1 algo que diferencia a TUROMAS dos restantes fabricantes de maquinaria para vidro \u00e9 a <strong>proximidade e o compromisso de estar sempre ao lado dos clientes, acompanhando-os antes, durante e depois de todo o processo de compra.<\/strong><\/p>\n<p>Este ano foi um ano complicado e dif\u00edcil para todos. Os eventos onde eram partilhadas novidades e novos avan\u00e7os foram cancelados e, com isso, tamb\u00e9m se perdeu o contacto mais pessoal.<\/p>\n<p>Por isso, a Turomas n\u00e3o quis renunciar a convidar alguns dos seus clientes mais especiais para as semanas IN!HOUSE nas instala\u00e7\u00f5es da empresa espanhola.<\/p>\n<p>As visitas decorreram entre os dias 23 de novembro e 11 de dezembro. Durante estes dias, diferentes empresas do setor do vidro puderam conhecer as instala\u00e7\u00f5es em primeira m\u00e3o, de uma forma exclusiva, segura e totalmente personalizada.<\/p>\n<p>Foram 13 dias em que foi poss\u00edvel conhecer toda a gama de produtos dispon\u00edvel em f\u00e1brica, al\u00e9m de partilhar experi\u00eancias e viv\u00eancias do setor do vidro num ano em que a pandemia marcou um antes e um depois nas rela\u00e7\u00f5es comerciais.<\/p>\n<p><strong>\u00c1lvaro Tom\u00e1s,<\/strong> vice-presidente da TUROMAS, destaca que estes dias <em>&#8220;foram uma boa oportunidade para conhecer por dentro todo o processo de fabrico das diferentes gamas de maquinaria. Este ano, e devido \u00e0 pandemia, n\u00e3o pudemos convidar todos aqueles que gostar\u00edamos, mas esperamos que 2021 nos permita voltar a partilhar convosco a nossa empresa e o seu ambiente.&#8221;<\/em><\/p>\n<p>Algumas das m\u00e1quinas que puderam ser vistas em funcionamento foram os <strong><a href=\"https:\/\/www.turomas.com\/maquinaria\/almacenes-inteligentes\/la\/\" target=\"_blank\" rel=\"noopener noreferrer\">carregadores a\u00e9reos LA-06<\/a><\/strong> da TUROMAS. Um produto em que se apostou em 2018, desenvolvendo uma gama totalmente nova e melhorada, que posicionou clientes nacionais e internacionais como l\u00edderes no setor do vidro.<\/p>\n<p>Al\u00e9m dos carregadores LA, as empresas visitantes puderam ver em primeira m\u00e3o o novo sistema de decapagem para vidro com prote\u00e7\u00e3o TPF e <strong><a href=\"https:\/\/www.saint-gobain-glass.com\/products\/easypro\" target=\"_blank\" rel=\"noopener noreferrer\">EASYPRO\u00ae<\/a><\/strong>. Um sistema que foi um fator determinante no processo de compra de alguns dos processadores de vidro mais importantes da Europa.<\/p>\n<p>Este opcional incorpora uma avan\u00e7ada t\u00e9cnica de v\u00e1cuo que aspira qualquer res\u00edduo resultante do processo de decapagem, al\u00e9m de a remo\u00e7\u00e3o da camada ser realizada numa \u00fanica passagem, melhorando o tempo de ciclo e o desgaste das m\u00f3s.<\/p>\n<p>O inovador sistema de decapagem p\u00f4de ser visto implementado no novo modelo de m\u00e1quina para corte de vidro monol\u00edtico de 6 metros. Este novo modelo foi desenhado para mudar a \u201cperspetiva\u201d de qualquer processador de vidro, sendo a otimiza\u00e7\u00e3o do espa\u00e7o e a integra\u00e7\u00e3o com a nova gera\u00e7\u00e3o de <a href=\"https:\/\/www.turomas.com\/maquinaria\/almacenes-inteligentes\/sr\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>armaz\u00e9ns autom\u00e1ticos \u2013 <\/strong><strong>tipo Rack-Shuttle SR <\/strong><\/a> duas das suas principais vantagens competitivas.<\/p>\n<p>Esta nova gama de produtos ser\u00e1 apresentada em 2021 e, em particular, na <strong><a href=\"https:\/\/www.glasstec-online.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Glasstec 2021.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Turomas celebr\u00f3 las jornadas IN!HOUSE haciendo participes a sus clientes m\u00e1s especiales de las ultimas novedades en procesado de vidrio plano<\/p>\n","protected":false},"author":1,"featured_media":5050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3,4],"tags":[],"class_list":["post-4668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turomas-in-the-world","category-turomas-news","category-turomas-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada | Turomas PT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada | Turomas PT\" \/>\n<meta property=\"og:description\" content=\"Turomas celebr\u00f3 las jornadas IN!HOUSE haciendo participes a sus clientes m\u00e1s especiales de las ultimas novedades en procesado de vidrio plano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/\" \/>\n<meta property=\"og:site_name\" content=\"Turomas PT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turomas.machinery\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T11:36:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T09:40:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"turomas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@turomas\" \/>\n<meta name=\"twitter:site\" content=\"@turomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"turomas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/\"},\"author\":{\"name\":\"turomas_admin\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"headline\":\"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada\",\"datePublished\":\"2026-01-13T11:36:40+00:00\",\"dateModified\":\"2026-04-01T09:40:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/\"},\"wordCount\":474,\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp\",\"articleSection\":[\"TUROMAS IN THE WORLD\",\"TUROMAS NEWS\",\"TUROMAS TECHNOLOGY\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/\",\"name\":\"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada | Turomas PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp\",\"datePublished\":\"2026-01-13T11:36:40+00:00\",\"dateModified\":\"2026-04-01T09:40:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp\",\"contentUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\",\"name\":\"Turomas PT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turomas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\",\"name\":\"turomas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"caption\":\"turomas_admin\"},\"sameAs\":[\"https:\\\/\\\/turomas.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada | Turomas PT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/","og_locale":"pt_PT","og_type":"article","og_title":"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada | Turomas PT","og_description":"Turomas celebr\u00f3 las jornadas IN!HOUSE haciendo participes a sus clientes m\u00e1s especiales de las ultimas novedades en procesado de vidrio plano","og_url":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/","og_site_name":"Turomas PT","article_publisher":"https:\/\/www.facebook.com\/turomas.machinery","article_published_time":"2026-01-13T11:36:40+00:00","article_modified_time":"2026-04-01T09:40:07+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp","type":"image\/webp"}],"author":"turomas_admin","twitter_card":"summary_large_image","twitter_creator":"@turomas","twitter_site":"@turomas","twitter_misc":{"Escrito por":"turomas_admin","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/#article","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/"},"author":{"name":"turomas_admin","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"headline":"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada","datePublished":"2026-01-13T11:36:40+00:00","dateModified":"2026-04-01T09:40:07+00:00","mainEntityOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/"},"wordCount":474,"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp","articleSection":["TUROMAS IN THE WORLD","TUROMAS NEWS","TUROMAS TECHNOLOGY"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/","url":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/","name":"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada | Turomas PT","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/#primaryimage"},"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp","datePublished":"2026-01-13T11:36:40+00:00","dateModified":"2026-04-01T09:40:07+00:00","author":{"@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"breadcrumb":{"@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/#primaryimage","url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp","contentUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Clientes-TUROMAS-2-LD-1536x1024-1-3.webp","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/turomas.com\/pt\/blog\/semanas-in-house-turomas-abre-sus-portas-de-forma-exclusiva-segura-e-personalizada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turomas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Semanas IN!HOUSE, a TUROMAS abre as suas portas de forma exclusiva, segura e personalizada"}]},{"@type":"WebSite","@id":"https:\/\/turomas.com\/pt\/#website","url":"https:\/\/turomas.com\/pt\/","name":"Turomas PT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turomas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315","name":"turomas_admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","caption":"turomas_admin"},"sameAs":["https:\/\/turomas.com"]}]}},"_links":{"self":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/comments?post=4668"}],"version-history":[{"count":3,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4668\/revisions"}],"predecessor-version":[{"id":6248,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4668\/revisions\/6248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media\/5050"}],"wp:attachment":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media?parent=4668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/categories?post=4668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/tags?post=4668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}