{"id":4673,"date":"2026-01-13T12:36:40","date_gmt":"2026-01-13T11:36:40","guid":{"rendered":"https:\/\/turomas.com\/blog\/turomas-regresa-a-vitrum-2021-balance\/"},"modified":"2026-04-01T11:46:57","modified_gmt":"2026-04-01T09:46:57","slug":"turomas-regressa-vitrum-2021-balanco","status":"publish","type":"post","link":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/","title":{"rendered":"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o"},"content":{"rendered":"<h2>A Vitrum, a feira internacional especializada em maquinaria, equipamentos e instala\u00e7\u00f5es para processar vidro plano, realizou-se de 5 a 8 de outubro em Mil\u00e3o. A Turomas, fabricante espanhola de maquinaria, participou como expositora ap\u00f3s dois anos sem atividade feiral.<\/h2>\n<p>O encontro bienal foi a primeira feira p\u00f3s-pandemia do setor do vidro europeu. Depois deste isolamento, a Vitrum foi respons\u00e1vel por devolver ao mercado clientes e fornecedores de forma r\u00e1pida, segura e eficaz. Um ponto de encontro onde se colocou em evid\u00eancia a realidade do setor e os desafios que enfrentar\u00e1 no pr\u00f3ximo ano.<\/p>\n<p>A TUROMAS esteve representada por Antonio Ortega, Diretor-Geral; \u00c1lvaro Tom\u00e1s, vice-presidente da TUROMAS; \u00c1lvaro Do\u00f1ate, Diretor Comercial de Espanha e Portugal; Oriol Llorens, Diretor Comercial da Europa; e Teresa Catal\u00e1n, Respons\u00e1vel de Marketing.<\/p>\n<p>Os visitantes que se aproximaram do stand tiveram a oportunidade de conhecer com mais detalhe a gama completa de maquinaria standard para vidro monol\u00edtico, vidro laminado e armazenamento inteligente, bem como as solu\u00e7\u00f5es personalizadas que a TUROMAS oferece.<\/p>\n<p>Em concreto, o encontro permitiu \u00e0 empresa espanhola dar a conhecer avan\u00e7os e inova\u00e7\u00f5es desenvolvidos ao longo do \u00faltimo ano: a nova gera\u00e7\u00e3o de sistemas de decapagem e o novo modelo de mesa de carga e corte para vidro de 6 metros \u2013 RUBI 406VA.<\/p>\n<p>A maioria das visitas provinha de pa\u00edses europeus. Em concreto, os projetos e reuni\u00f5es mais relevantes vieram do Reino Unido, Irlanda, Chipre, Portugal, Espanha, R\u00fassia, Ucr\u00e2nia, Gr\u00e9cia, Rom\u00e9nia, S\u00e9rvia, B\u00f3snia e Herzegovina e Fran\u00e7a, embora tamb\u00e9m tenha havido representa\u00e7\u00e3o sul-africana.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_699203683\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/15f320cb-a78e-4537-85ce-3c47255c2408-1024x768-3.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/15f320cb-a78e-4537-85ce-3c47255c2408-1024x768-3.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/15f320cb-a78e-4537-85ce-3c47255c2408-1024x768-3-300x225.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/15f320cb-a78e-4537-85ce-3c47255c2408-1024x768-3-768x576.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_699203683 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p>A participa\u00e7\u00e3o da empresa de Teruel na exposi\u00e7\u00e3o internacional foi gratificante e proveitosa. Apesar de ter sido o primeiro contacto com as feiras presenciais ap\u00f3s a pandemia, a equipa comercial mostrou-se satisfeita com a assist\u00eancia e a rece\u00e7\u00e3o na feira, j\u00e1 que a aflu\u00eancia de clientes foi controlada, mas de elevada qualidade.<\/p>\n<p>Vitrum 2021 serviu para confirmar que, apesar da paragem provocada pela COVID, as empresas do setor continuar\u00e3o a apostar neste formato de eventos presenciais. Foram e continuar\u00e3o a ser uma parte essencial do neg\u00f3cio, permitindo oferecer uma grande montra comercial, bem como uma elevada repercuss\u00e3o internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vitrum, la feria internacional especializada en maquinaria, equipos y plantas para procesar vidrio plano se celebr\u00f3 del 5 al 8 de octubre en Mil\u00e1n. Turomas, fabricante espa\u00f1ol de maquinaria particip\u00f3 como expositor despu\u00e9s de dos a\u00f1os sin actividad ferial.<\/p>\n","protected":false},"author":1,"featured_media":5055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3,4],"tags":[],"class_list":["post-4673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turomas-in-the-world","category-turomas-news","category-turomas-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o | Turomas PT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o | Turomas PT\" \/>\n<meta property=\"og:description\" content=\"Vitrum, la feria internacional especializada en maquinaria, equipos y plantas para procesar vidrio plano se celebr\u00f3 del 5 al 8 de octubre en Mil\u00e1n. Turomas, fabricante espa\u00f1ol de maquinaria particip\u00f3 como expositor despu\u00e9s de dos a\u00f1os sin actividad ferial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/\" \/>\n<meta property=\"og:site_name\" content=\"Turomas PT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turomas.machinery\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T11:36:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T09:46:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Vitrum-4-WEB-1536x1024-1-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"turomas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@turomas\" \/>\n<meta name=\"twitter:site\" content=\"@turomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"turomas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/\"},\"author\":{\"name\":\"turomas_admin\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"headline\":\"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o\",\"datePublished\":\"2026-01-13T11:36:40+00:00\",\"dateModified\":\"2026-04-01T09:46:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/\"},\"wordCount\":391,\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Vitrum-4-WEB-1536x1024-1-3.webp\",\"articleSection\":[\"TUROMAS IN THE WORLD\",\"TUROMAS NEWS\",\"TUROMAS TECHNOLOGY\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/\",\"name\":\"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o | Turomas PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Vitrum-4-WEB-1536x1024-1-3.webp\",\"datePublished\":\"2026-01-13T11:36:40+00:00\",\"dateModified\":\"2026-04-01T09:46:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Vitrum-4-WEB-1536x1024-1-3.webp\",\"contentUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Vitrum-4-WEB-1536x1024-1-3.webp\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-regressa-vitrum-2021-balanco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\",\"name\":\"Turomas PT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turomas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\",\"name\":\"turomas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"caption\":\"turomas_admin\"},\"sameAs\":[\"https:\\\/\\\/turomas.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o | Turomas PT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/","og_locale":"pt_PT","og_type":"article","og_title":"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o | Turomas PT","og_description":"Vitrum, la feria internacional especializada en maquinaria, equipos y plantas para procesar vidrio plano se celebr\u00f3 del 5 al 8 de octubre en Mil\u00e1n. Turomas, fabricante espa\u00f1ol de maquinaria particip\u00f3 como expositor despu\u00e9s de dos a\u00f1os sin actividad ferial.","og_url":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/","og_site_name":"Turomas PT","article_publisher":"https:\/\/www.facebook.com\/turomas.machinery","article_published_time":"2026-01-13T11:36:40+00:00","article_modified_time":"2026-04-01T09:46:57+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Vitrum-4-WEB-1536x1024-1-3.webp","type":"image\/webp"}],"author":"turomas_admin","twitter_card":"summary_large_image","twitter_creator":"@turomas","twitter_site":"@turomas","twitter_misc":{"Escrito por":"turomas_admin","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/#article","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/"},"author":{"name":"turomas_admin","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"headline":"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o","datePublished":"2026-01-13T11:36:40+00:00","dateModified":"2026-04-01T09:46:57+00:00","mainEntityOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/"},"wordCount":391,"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Vitrum-4-WEB-1536x1024-1-3.webp","articleSection":["TUROMAS IN THE WORLD","TUROMAS NEWS","TUROMAS TECHNOLOGY"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/","url":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/","name":"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o | Turomas PT","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/#primaryimage"},"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Vitrum-4-WEB-1536x1024-1-3.webp","datePublished":"2026-01-13T11:36:40+00:00","dateModified":"2026-04-01T09:46:57+00:00","author":{"@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"breadcrumb":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/#primaryimage","url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Vitrum-4-WEB-1536x1024-1-3.webp","contentUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Vitrum-4-WEB-1536x1024-1-3.webp","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-regressa-vitrum-2021-balanco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turomas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"A Turomas regressa \u00e0 Vitrum 2021. Balan\u00e7o"}]},{"@type":"WebSite","@id":"https:\/\/turomas.com\/pt\/#website","url":"https:\/\/turomas.com\/pt\/","name":"Turomas PT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turomas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315","name":"turomas_admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","caption":"turomas_admin"},"sameAs":["https:\/\/turomas.com"]}]}},"_links":{"self":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/comments?post=4673"}],"version-history":[{"count":3,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4673\/revisions"}],"predecessor-version":[{"id":6252,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4673\/revisions\/6252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media\/5055"}],"wp:attachment":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media?parent=4673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/categories?post=4673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/tags?post=4673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}