{"id":4696,"date":"2026-01-13T12:36:43","date_gmt":"2026-01-13T11:36:43","guid":{"rendered":"https:\/\/turomas.com\/blog\/turomas-y-arquetipo-mas-de-treinta-anos-unidos-en-el-sector-del-vidrio\/"},"modified":"2026-03-31T15:33:52","modified_gmt":"2026-03-31T13:33:52","slug":"turomas-arquetipo-mais-de-trinta-anos-setor-vidro","status":"publish","type":"post","link":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/","title":{"rendered":"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro"},"content":{"rendered":"<blockquote>\n<p>Com um percurso de mais de 30 anos a confiar na TUROMAS, a empresa chilena comprova o seu compromisso e experi\u00eancia no mercado chileno. Conta com mais de 25 m\u00e1quinas da empresa espanhola e, desde o in\u00edcio, tem estado em constante evolu\u00e7\u00e3o, sempre \u00e0 procura de oferecer a melhor e mais completa gama de solu\u00e7\u00f5es aos seus clientes.<\/p>\n<\/blockquote>\n\n<p><iframe loading=\"lazy\" class=\"elementor-video\" frameborder=\"0\" allowfullscreen=\"\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" title=\"TUROMAS in the world ARQUETIPO\" width=\"100%\" height=\"500\" src=\"https:\/\/www.youtube.com\/embed\/4zcUmgMDki4?controls=1&amp;rel=0&amp;playsinline=0&amp;cc_load_policy=0&amp;autoplay=1&amp;enablejsapi=1&amp;origin=https%3A%2F%2Fwww.turomas.com&amp;widgetid=1&amp;forigin=https%3A%2F%2Fwww.turomas.com%2Fturomas-y-arquetipo-mas-de-treinta-anos-unidos-en-el-sector-del-vidrio%2F&amp;aoriginsup=1&amp;gporigin=https%3A%2F%2Fwww.turomas.com%2Fnoticias%2F&amp;vf=1\" id=\"widget2\" data-gtm-yt-inspected-9=\"true\"><\/iframe><br \/>\n\n<p>A Arquetipo nasceu com uma vis\u00e3o clara: transformar lares atrav\u00e9s da qualidade e da inova\u00e7\u00e3o dos seus produtos. Come\u00e7ou com o fabrico de janelas personalizadas, que rapidamente ganharam reconhecimento pelo seu estilo e durabilidade. Com o tempo, a Arquetipo tornou-se sin\u00f3nimo de eleg\u00e2ncia e excel\u00eancia no mercado chileno da constru\u00e7\u00e3o e do design.<\/p>\n<p>Dois anos ap\u00f3s a sua funda\u00e7\u00e3o, a empresa deparou-se com um novo desafio. \u00c0 medida que a procura aumentava, percebeu que, para manter a qualidade dos seus produtos e cumprir os prazos de entrega, tinha de dominar o processo de corte de vidro. Esse foi um ponto de viragem que a levou a investir em tecnologia de vanguarda, e foi ent\u00e3o que surgiu o fabricante espanhol TUROMAS.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_640535784\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/arquetipo-8-1024x683-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/arquetipo-8-1024x683-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/arquetipo-8-1024x683-2-300x200.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/arquetipo-8-1024x683-2-768x512.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_640535784 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h6><strong><em>A empresa Arquetipo, em Santiago do Chile<\/em><\/strong><\/h6>\n<blockquote>\n<p>\n\t\tFal\u00e1mos com Joaqu\u00edn Baeza, diretor-geral da empresa.\n\t<\/p>\n<\/blockquote>\n<p>Ainda me lembro quando compr\u00e1mos a primeira mesa de laminado. Na verdade, eu n\u00e3o sou t\u00e9cnico, sou comercial, por isso contava ao Miguel o que precisava e ele dizia-me: \u201cJoaqu\u00edn, esta \u00e9 a mesa de que precisas.\u201d E assim foi. Uma das primeiras mesas que a TUROMAS fabricou para cortar vidro laminado foi comprada por n\u00f3s.<br \/>\n<cite>Joaqu\u00edn BaezaDiretor-Geral da Arquetipo<\/cite><\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_465678859\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Alvaro-Joaquin-Eduardo-1024x683-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Alvaro-Joaquin-Eduardo-1024x683-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Alvaro-Joaquin-Eduardo-1024x683-2-300x200.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Alvaro-Joaquin-Eduardo-1024x683-2-768x512.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_465678859 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h6>\u00c1lvaro Tom\u00e1s, Vice-presidente da TUROMAS; Joaqu\u00edn Baeza, Diretor-Geral da Arquetipo; e Eduardo Nieto, Delegado comercial da TUROMAS no Chile.<\/h6>\n<p>A paix\u00e3o pela qualidade e pela inova\u00e7\u00e3o continuou a impulsionar a Arquetipo ao longo das d\u00e9cadas. A empresa n\u00e3o se concentrou apenas na melhoria constante dos seus produtos, mas tamb\u00e9m na expans\u00e3o da sua presen\u00e7a. Atualmente, a Arquetipo conta com cinco sucursais localizadas em Santiago, Valpara\u00edso, Antofagasta, Coquimbo e Talca. Esta expans\u00e3o n\u00e3o s\u00f3 garante uma s\u00f3lida presen\u00e7a nacional, como tamb\u00e9m permite \u00e0 empresa entregar os seus produtos de forma r\u00e1pida e segura em todo o pa\u00eds.<i><\/i><\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_161745233\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/arquetipo-3-1.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/arquetipo-3-1.webp 600w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/arquetipo-3-1-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_161745233 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h6>Operador em LAM 304<\/h6>\n<p>A vida ensinou-me que, quando se constr\u00f3i uma rela\u00e7\u00e3o a longo prazo, tudo funciona bem. Com os meus fornecedores tem funcionado muito bem. Sou cliente da TUROMAS desde os nossos in\u00edcios, com todos os altos e baixos que uma rela\u00e7\u00e3o pode ter. (\u2026) O Miguel e eu percebemos que cada um estava a criar o seu neg\u00f3cio do zero e fomos crescendo juntos.<br \/>\n<cite>Joaqu\u00edn BaezaDiretor-Geral da Arquetipo<\/cite><\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_727066186\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-1024x683-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-1024x683-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-1024x683-2-300x200.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-1024x683-2-768x512.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_727066186 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h6>Joaqu\u00edn Baeza, diretor-geral da Arquetipo<\/h6>\n<p>Ao longo do ano passado, em 2022, a Arquetipo reafirmou a sua confian\u00e7a na TUROMAS ao optar por colaborar novamente num passo significativo: <b>come\u00e7ar a trabalhar com vidro jumbo.<\/b> Este marco concretizou-se atrav\u00e9s da aquisi\u00e7\u00e3o da mais recente e avan\u00e7ada linha de maquinaria de armazenamento autom\u00e1tico e corte de vidro oferecida pela TUROMAS.<\/p>\n<p>Esta colabora\u00e7\u00e3o estrat\u00e9gica refor\u00e7a ainda mais a posi\u00e7\u00e3o da Arquetipo como l\u00edder na ind\u00fastria, permitindo-lhe manter o seu compromisso de oferecer produtos da mais alta qualidade.<\/p>\n<blockquote>\n<p>\n\t\tInova\u00e7\u00e3o em maquinaria\n\t<\/p>\n<\/blockquote>\n<p>As m\u00e1quinas instaladas na empresa chilena s\u00e3o compostas por um sistema inteligente de armazenamento de vidro tipo rack shuttle SR-06 para vidros de 6100 x 3300 mm (240\u201d x 130\u201d). Trata-se de uma solu\u00e7\u00e3o de armazenamento inteligente de vidro jumbo que combina efici\u00eancia e versatilidade, oferecendo tempos de ciclo m\u00ednimos e capacidade para trabalhar com diferentes espessuras, camadas e tamanhos, bem como op\u00e7\u00f5es de capacidade de carga ajust\u00e1veis. Esta m\u00e1quina destaca-se pela sua avan\u00e7ada tecnologia de controlo, oferecendo uma velocidade e precis\u00e3o not\u00e1veis que reduzem significativamente o tempo de carga e aumentam a produtividade de forma eficaz.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_324294042\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Instalacion-completa-1024x576-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Instalacion-completa-1024x576-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Instalacion-completa-1024x576-2-300x169.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Instalacion-completa-1024x576-2-768x432.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_324294042 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p>Instala\u00e7\u00e3o completa: SR-06, RUBI 406VA e LAM 304<\/p>\n<p>Juntamente com o armaz\u00e9m SR-06, foi instalada uma mesa de corte monol\u00edtico RUBI 406VA. O seu inovador design de carga autom\u00e1tica integra-se na pr\u00f3pria estrutura da mesa de corte, otimizando os processos de carga, posicionamento, corte e evacua\u00e7\u00e3o ou separa\u00e7\u00e3o, permitindo responder \u00e0s necessidades com m\u00e1xima produtividade e automatiza\u00e7\u00e3o em apenas 35 m\u00b2.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_320156042\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/RUBI-406VA-1024x576-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/RUBI-406VA-1024x576-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/RUBI-406VA-1024x576-2-300x169.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/RUBI-406VA-1024x576-2-768x432.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_320156042 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p>Mesa de corte autom\u00e1tico RUBI 406VA<\/p>\n<p>Para completar a instala\u00e7\u00e3o, foi acrescentada uma segunda linha de carga e corte para vidro laminado standard: LAM 304 + MV300. Concebida de forma compacta, realiza a carga, decapagem, corte, separa\u00e7\u00e3o e desmembramento de forma excecional em vidro at\u00e9 10+10 mm de espessura, mesmo em vidros com butiral de elevada dureza e rigidez.<\/p>\n<p>Uma combina\u00e7\u00e3o de caracter\u00edsticas e tecnologias que garante um corte de vidro eficiente, preciso e de alta qualidade. Desde o seu design robusto at\u00e9 ao seu sistema de controlo avan\u00e7ado, cada elemento foi concebido para otimizar o processo de corte e melhorar a produtividade na manipula\u00e7\u00e3o de vidro em diferentes aplica\u00e7\u00f5es industriais.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_743962198\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Arquetipo-instalacion-1024x576-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Arquetipo-instalacion-1024x576-2.webp 1024w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Arquetipo-instalacion-1024x576-2-300x169.webp 300w, https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Arquetipo-instalacion-1024x576-2-768x432.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_743962198 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p>LAM 304 + MV 300<\/p>\n<p>Estas mesas automatizadas com tecnologia de vanguarda permitem \u00e0 Arquetipo garantir a m\u00e1xima efici\u00eancia no corte de chapas de vidro monol\u00edtico e laminado em cada uma das suas sucursais. Atrav\u00e9s da utiliza\u00e7\u00e3o de software especializado, \u00e9 poss\u00edvel maximizar o aproveitamento do material, o que gera grandes poupan\u00e7as para os seus clientes.<\/p>\n<p>Outro dos aspetos que refor\u00e7am esta alian\u00e7a \u00e9 o servi\u00e7o t\u00e9cnico. A TUROMAS disp\u00f5e de servi\u00e7o t\u00e9cnico e comercial direto no Chile, o que lhe permite criar e manter v\u00ednculos pr\u00f3ximos e s\u00f3lidos com os seus clientes.<\/p>\n<p>A TUROMAS teve a capacidade de construir uma alian\u00e7a muito forte com as pessoas. Hoje em dia, \u00e9 a linha de mesas e de armaz\u00e9ns inteligentes mais pr\u00f3xima de n\u00f3s. Eu confio na TUROMAS. Agora j\u00e1 est\u00e1 a segunda gera\u00e7\u00e3o, e conseguiu manter essa proximidade, e creio que isso \u00e9 fundamental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un trayecto de m\u00e1s de 30 a\u00f1os confiando en TUROMAS, la empresa chilena avala su compromiso y experiencia en el mercado chileno. Cuenta con m\u00e1s de 25 m\u00e1quinas de la firma espa\u00f1ola y desde los inicios han estado en una constante evoluci\u00f3n, siempre en la b\u00fasqueda de entregar la mejor y m\u00e1s completa oferta de soluciones para sus clientes.<\/p>\n","protected":false},"author":1,"featured_media":5017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3,4],"tags":[],"class_list":["post-4696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turomas-in-the-world","category-turomas-news","category-turomas-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro | Turomas PT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro | Turomas PT\" \/>\n<meta property=\"og:description\" content=\"Con un trayecto de m\u00e1s de 30 a\u00f1os confiando en TUROMAS, la empresa chilena avala su compromiso y experiencia en el mercado chileno. Cuenta con m\u00e1s de 25 m\u00e1quinas de la firma espa\u00f1ola y desde los inicios han estado en una constante evoluci\u00f3n, siempre en la b\u00fasqueda de entregar la mejor y m\u00e1s completa oferta de soluciones para sus clientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/\" \/>\n<meta property=\"og:site_name\" content=\"Turomas PT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turomas.machinery\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T11:36:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T13:33:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-768x512-1-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"turomas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@turomas\" \/>\n<meta name=\"twitter:site\" content=\"@turomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"turomas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/\"},\"author\":{\"name\":\"turomas_admin\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"headline\":\"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro\",\"datePublished\":\"2026-01-13T11:36:43+00:00\",\"dateModified\":\"2026-03-31T13:33:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/\"},\"wordCount\":1062,\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Joaquin-Baeza-768x512-1-3.webp\",\"articleSection\":[\"TUROMAS IN THE WORLD\",\"TUROMAS NEWS\",\"TUROMAS TECHNOLOGY\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/\",\"name\":\"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro | Turomas PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Joaquin-Baeza-768x512-1-3.webp\",\"datePublished\":\"2026-01-13T11:36:43+00:00\",\"dateModified\":\"2026-03-31T13:33:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Joaquin-Baeza-768x512-1-3.webp\",\"contentUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Joaquin-Baeza-768x512-1-3.webp\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\",\"name\":\"Turomas PT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turomas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\",\"name\":\"turomas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"caption\":\"turomas_admin\"},\"sameAs\":[\"https:\\\/\\\/turomas.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro | Turomas PT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/","og_locale":"pt_PT","og_type":"article","og_title":"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro | Turomas PT","og_description":"Con un trayecto de m\u00e1s de 30 a\u00f1os confiando en TUROMAS, la empresa chilena avala su compromiso y experiencia en el mercado chileno. Cuenta con m\u00e1s de 25 m\u00e1quinas de la firma espa\u00f1ola y desde los inicios han estado en una constante evoluci\u00f3n, siempre en la b\u00fasqueda de entregar la mejor y m\u00e1s completa oferta de soluciones para sus clientes.","og_url":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/","og_site_name":"Turomas PT","article_publisher":"https:\/\/www.facebook.com\/turomas.machinery","article_published_time":"2026-01-13T11:36:43+00:00","article_modified_time":"2026-03-31T13:33:52+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-768x512-1-3.webp","type":"image\/webp"}],"author":"turomas_admin","twitter_card":"summary_large_image","twitter_creator":"@turomas","twitter_site":"@turomas","twitter_misc":{"Escrito por":"turomas_admin","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/#article","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/"},"author":{"name":"turomas_admin","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"headline":"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro","datePublished":"2026-01-13T11:36:43+00:00","dateModified":"2026-03-31T13:33:52+00:00","mainEntityOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/"},"wordCount":1062,"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-768x512-1-3.webp","articleSection":["TUROMAS IN THE WORLD","TUROMAS NEWS","TUROMAS TECHNOLOGY"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/","url":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/","name":"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro | Turomas PT","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/#primaryimage"},"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-768x512-1-3.webp","datePublished":"2026-01-13T11:36:43+00:00","dateModified":"2026-03-31T13:33:52+00:00","author":{"@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"breadcrumb":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/#primaryimage","url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-768x512-1-3.webp","contentUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/Joaquin-Baeza-768x512-1-3.webp","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-arquetipo-mais-de-trinta-anos-setor-vidro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turomas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"TUROMAS e ARQUETIPO: mais de trinta anos unidos no setor do vidro"}]},{"@type":"WebSite","@id":"https:\/\/turomas.com\/pt\/#website","url":"https:\/\/turomas.com\/pt\/","name":"Turomas PT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turomas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315","name":"turomas_admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","caption":"turomas_admin"},"sameAs":["https:\/\/turomas.com"]}]}},"_links":{"self":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/comments?post=4696"}],"version-history":[{"count":3,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4696\/revisions"}],"predecessor-version":[{"id":6083,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4696\/revisions\/6083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media\/5017"}],"wp:attachment":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media?parent=4696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/categories?post=4696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/tags?post=4696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}