{"id":4713,"date":"2026-01-13T12:36:46","date_gmt":"2026-01-13T11:36:46","guid":{"rendered":"https:\/\/turomas.com\/blog\/vidres-ponent-renueva-el-proceso-de-almacenamiento-carga-y-corte-de-vidrio-con-tecnologia-turomas-optimizando-la-capacidad-de-almacenaje-en-mas-de-1000m2\/"},"modified":"2026-03-23T12:02:14","modified_gmt":"2026-03-23T11:02:14","slug":"vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas","status":"publish","type":"post","link":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/","title":{"rendered":"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2"},"content":{"rendered":"<h2>A Vidres Ponent, S.L., fundada em 1992 em Torrefarrera, Lleida, \u00e9 uma empresa especializada no fabrico e transforma\u00e7\u00e3o de vidro plano para a constru\u00e7\u00e3o e a arquitetura. Ao longo de mais de tr\u00eas d\u00e9cadas, consolidou a sua presen\u00e7a no mercado, destacando-se pelo seu compromisso com a qualidade, a inova\u00e7\u00e3o e a sustentabilidade.<\/h2>\n<p>Com o objetivo de otimizar a efici\u00eancia operacional e aumentar a capacidade produtiva, a <a href=\"https:\/\/vidresponent.cat\/es\/\">Vidres Ponent<\/a> realizou um importante investimento em maquinaria TUROMAS. Em concreto, foi instalado um <strong><a href=\"https:\/\/www.turomas.com\/maquinaria\/almacenes-inteligentes\/la\/#LA-06\">LA-06<\/a><\/strong> armaz\u00e9m inteligente do tipo carregador a\u00e9reo, juntamente com dois classificadores autom\u00e1ticos <strong>SC-06<\/strong>, com uma capacidade total de 576 Tn distribu\u00eddas por 76 posi\u00e7\u00f5es. No que diz respeito ao corte, foram instaladas duas linhas de corte: uma para vidro monol\u00edtico, a <a href=\"https:\/\/www.turomas.com\/maquinaria\/corte-vidrio-monolitico\/rubi-300-series\/rubi-303c\/\">RUBI 303C<\/a>, e uma linha mista para vidro laminado composta por uma RUBI <a href=\"https:\/\/www.turomas.com\/maquinaria\/corte-vidrio-monolitico\/rubi-300-series\/rubi-306tc\/\">306TC<\/a> + <a href=\"https:\/\/www.turomas.com\/maquinaria\/corte-vidrio-laminado\/lam-300-series\/lam-304\/\">LAM304<\/a>.<\/p>\n<p>\n\u201cNa Vidres Ponent, preocupamo-nos especialmente com a produtividade e com a melhoria dos nossos processos. Na nossa procura constante por melhorar a cadeia de produ\u00e7\u00e3o e reorganizar a f\u00e1brica, surgiu a necessidade de contactar a TUROMAS para concretizar o nosso projeto.\u201d<br \/>\n<cite>Jordi TorreguitartGerente da Vidres Ponent<\/cite>\n<\/p>\n<p>Fal\u00e1mos com Jordi, da Vidres Ponent, para conhecer melhor a sua hist\u00f3ria, filosofia e os motivos por detr\u00e1s desta decis\u00e3o estrat\u00e9gica:<\/p>\n<h5 style=\"text-align: center\"><strong>Entrevista da TUROMAS a <\/strong><strong>Jordi Torreguitart, Gerente da Vidres Ponent<\/strong><\/h5>\n<p><strong>O que \u00e9 a Vidres Ponent, S.L.?<\/strong><\/p>\n<p><em>A Vidres Ponent, S.L. \u00e9 uma empresa especializada no fabrico e transforma\u00e7\u00e3o de vidro para a constru\u00e7\u00e3o e a arquitetura. Fundada em 1992, foi evoluindo ao longo dos anos, superando grandes desafios como a crise de 2008 e a pandemia de 2020, at\u00e9 se consolidar como uma refer\u00eancia em qualidade, tecnologia e inova\u00e7\u00e3o no setor do vidro.<\/em><\/p>\n<p><em>A nossa vis\u00e3o \u00e9 clara: oferecer produtos de alta qualidade com um servi\u00e7o pr\u00f3ximo e eficiente. Apostamos na excel\u00eancia em cada processo, desde a sele\u00e7\u00e3o de mat\u00e9rias-primas at\u00e9 ao fabrico e ao acompanhamento p\u00f3s-venda. Acreditamos na sustentabilidade do vidro como material recicl\u00e1vel e infinito, e trabalhamos com a Guardian Glass, assegurando padr\u00f5es de qualidade de primeiro n\u00edvel.<\/em><\/p>\n<p><em>Na Vidres Ponent, a inova\u00e7\u00e3o e a aten\u00e7\u00e3o ao cliente s\u00e3o pilares fundamentais. Diferenciamo-nos por oferecer vidro com perfil espa\u00e7ador preto de s\u00e9rie, sem custos adicionais, garantindo uma melhor est\u00e9tica e efici\u00eancia t\u00e9rmica. Al\u00e9m disso, damos prioridade \u00e0 transpar\u00eancia e \u00e0 confian\u00e7a com os nossos clientes, acompanhando-os em todos os momentos com um servi\u00e7o personalizado.<\/em><\/p>\n<p><em>Hoje, a Vidres Ponent continua a crescer com a mesma ess\u00eancia com que nasceu: cuidando das pessoas, da equipa e dos nossos clientes, porque sabemos que juntos podemos continuar a construir um futuro s\u00f3lido e brilhante.<\/em><\/p>\n<p><strong>Como surgiu a necessidade das novas m\u00e1quinas de corte da TUROMAS?<\/strong><\/p>\n<p><em>Na Vidres Ponent, preocupamo-nos especialmente com a produtividade e com a melhoria dos nossos processos. Na nossa procura constante por melhorar a cadeia de produ\u00e7\u00e3o e reorganizar a f\u00e1brica, surgiu a necessidade de contactar a TUROMAS para concretizar o nosso projeto.<\/em><\/p>\n<p><em>A TUROMAS oferece-nos m\u00e1quinas precisas que permitem maior efici\u00eancia no trabalho e no tempo utilizado. S\u00e3o m\u00e1quinas de alto rendimento que satisfazem perfeitamente as nossas necessidades.<\/em><\/p>\n<p><strong>Que modelos de m\u00e1quinas TUROMAS foram instalados? Porque s\u00e3o estas m\u00e1quinas as mais adequadas para a Vidres Ponent, S.L.? O que destacaria nelas?<\/strong><\/p>\n<p><em>Na Vidres Ponent dispomos de tr\u00eas equipamentos TUROMAS:<\/em><\/p>\n<ol>\n<li><strong><em>LA-06 Carregador inteligente<\/em><\/strong><em>:<\/em><\/li>\n<\/ol>\n<p><em>Permite uma poupan\u00e7a significativa de tempo no processo de carga das chapas de vidro para as mesas de corte, otimizando a produ\u00e7\u00e3o e reduzindo os tempos mortos.<\/em><\/p>\n<p><em>Destacamos a sua capacidade de organiza\u00e7\u00e3o, conseguindo armazenar mais material em menos espa\u00e7o. Concretamente, conseguimos reduzir em 1.000 metros quadrados a superf\u00edcie destinada a armazenagem gra\u00e7as \u00e0 instala\u00e7\u00e3o de dois classificadores autom\u00e1ticos SC-06 com uma capacidade total de 576 Tn Jumbo distribu\u00eddas por 76 posi\u00e7\u00f5es (<\/em><em>56 unid. x 190 mm e <\/em><em>20 unid. x 350 mm).<\/em><\/p>\n<p><em>A sua integra\u00e7\u00e3o com o carregador LA-06 permitiu aumentar a produtividade da mesa de corte, otimizando o processo e reduzindo os tempos de manipula\u00e7\u00e3o.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>2. RUBI 303C mesa de corte para vidro monol\u00edtico<\/em><\/strong><em>: uma das mais r\u00e1pidas do mercado para o corte de vidro em chapa pequena. Incorpora correias tipo colmeia para evacuar e carregar o vidro de forma autom\u00e1tica, bem como um sistema de desbaste para vidros com camada de baixa emissividade.<\/em><\/p>\n<p><strong><em>3. Linha mista RUBI 306TC com LAM 304<\/em><\/strong><em>: linha de corte para vidro monol\u00edtico jumbo com ponte de corte para vidro laminado. <\/em><em>Ambas as pontes de corte est\u00e3o equipadas com sistema de desbaste para vidro de baixa emissividade.<\/em><\/p>\n<p><em>O seu fabrico nacional \u00e9 um valor acrescentado para n\u00f3s, j\u00e1 que apostamos em apoiar empresas que, tal como a nossa, operam no pa\u00eds.<\/em><\/p>\n<p><em>As m\u00e1quinas TUROMAS permitiram reorganizar a f\u00e1brica da Vidres Ponent, reduzindo espa\u00e7o e aumentando a efici\u00eancia. Gra\u00e7as a este investimento, conseguimos criar uma cadeia de produ\u00e7\u00e3o altamente competitiva, melhorando os prazos de entrega e elevando os padr\u00f5es de qualidade em cada projeto.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Vidres Ponent, S.L., fundada em 1992 em Torrefarrera, Lleida, \u00e9 uma empresa especializada no fabrico e transforma\u00e7\u00e3o de vidro plano para a constru\u00e7\u00e3o e a arquitetura. Ao longo de mais de tr\u00eas d\u00e9cadas, consolidou a sua presen\u00e7a no mercado, destacando-se pelo seu compromisso com a qualidade, a inova\u00e7\u00e3o e a sustentabilidade. Com o objetivo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3,4],"tags":[],"class_list":["post-4713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turomas-in-the-world","category-turomas-news","category-turomas-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2 | Turomas PT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2 | Turomas PT\" \/>\n<meta property=\"og:description\" content=\"A Vidres Ponent, S.L., fundada em 1992 em Torrefarrera, Lleida, \u00e9 uma empresa especializada no fabrico e transforma\u00e7\u00e3o de vidro plano para a constru\u00e7\u00e3o e a arquitetura. Ao longo de mais de tr\u00eas d\u00e9cadas, consolidou a sua presen\u00e7a no mercado, destacando-se pelo seu compromisso com a qualidade, a inova\u00e7\u00e3o e a sustentabilidade. Com o objetivo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/\" \/>\n<meta property=\"og:site_name\" content=\"Turomas PT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turomas.machinery\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T11:36:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T11:02:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/DRON-VIDRES-2-768x405-1-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"turomas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@turomas\" \/>\n<meta name=\"twitter:site\" content=\"@turomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"turomas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/\"},\"author\":{\"name\":\"turomas_admin\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"headline\":\"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2\",\"datePublished\":\"2026-01-13T11:36:46+00:00\",\"dateModified\":\"2026-03-23T11:02:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/\"},\"wordCount\":889,\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/DRON-VIDRES-2-768x405-1-3.jpg\",\"articleSection\":[\"TUROMAS IN THE WORLD\",\"TUROMAS NEWS\",\"TUROMAS TECHNOLOGY\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/\",\"name\":\"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2 | Turomas PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/DRON-VIDRES-2-768x405-1-3.jpg\",\"datePublished\":\"2026-01-13T11:36:46+00:00\",\"dateModified\":\"2026-03-23T11:02:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/DRON-VIDRES-2-768x405-1-3.jpg\",\"contentUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/DRON-VIDRES-2-768x405-1-3.jpg\",\"width\":768,\"height\":405},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\",\"name\":\"Turomas PT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turomas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\",\"name\":\"turomas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"caption\":\"turomas_admin\"},\"sameAs\":[\"https:\\\/\\\/turomas.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2 | Turomas PT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/","og_locale":"pt_PT","og_type":"article","og_title":"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2 | Turomas PT","og_description":"A Vidres Ponent, S.L., fundada em 1992 em Torrefarrera, Lleida, \u00e9 uma empresa especializada no fabrico e transforma\u00e7\u00e3o de vidro plano para a constru\u00e7\u00e3o e a arquitetura. Ao longo de mais de tr\u00eas d\u00e9cadas, consolidou a sua presen\u00e7a no mercado, destacando-se pelo seu compromisso com a qualidade, a inova\u00e7\u00e3o e a sustentabilidade. Com o objetivo...","og_url":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/","og_site_name":"Turomas PT","article_publisher":"https:\/\/www.facebook.com\/turomas.machinery","article_published_time":"2026-01-13T11:36:46+00:00","article_modified_time":"2026-03-23T11:02:14+00:00","og_image":[{"width":768,"height":405,"url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/DRON-VIDRES-2-768x405-1-3.jpg","type":"image\/jpeg"}],"author":"turomas_admin","twitter_card":"summary_large_image","twitter_creator":"@turomas","twitter_site":"@turomas","twitter_misc":{"Escrito por":"turomas_admin","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/#article","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/"},"author":{"name":"turomas_admin","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"headline":"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2","datePublished":"2026-01-13T11:36:46+00:00","dateModified":"2026-03-23T11:02:14+00:00","mainEntityOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/"},"wordCount":889,"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/DRON-VIDRES-2-768x405-1-3.jpg","articleSection":["TUROMAS IN THE WORLD","TUROMAS NEWS","TUROMAS TECHNOLOGY"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/","url":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/","name":"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2 | Turomas PT","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/#primaryimage"},"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/DRON-VIDRES-2-768x405-1-3.jpg","datePublished":"2026-01-13T11:36:46+00:00","dateModified":"2026-03-23T11:02:14+00:00","author":{"@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"breadcrumb":{"@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/#primaryimage","url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/DRON-VIDRES-2-768x405-1-3.jpg","contentUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/DRON-VIDRES-2-768x405-1-3.jpg","width":768,"height":405},{"@type":"BreadcrumbList","@id":"https:\/\/turomas.com\/pt\/blog\/vidres-ponent-renova-armazenamento-carga-corte-vidro-tecnologia-turomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turomas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"A Vidres Ponent renova o processo de armazenamento, carga e corte de vidro com tecnologia TUROMAS, otimizando a capacidade de armazenagem em mais de 1.000 m\u00b2"}]},{"@type":"WebSite","@id":"https:\/\/turomas.com\/pt\/#website","url":"https:\/\/turomas.com\/pt\/","name":"Turomas PT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turomas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315","name":"turomas_admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","caption":"turomas_admin"},"sameAs":["https:\/\/turomas.com"]}]}},"_links":{"self":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/comments?post=4713"}],"version-history":[{"count":1,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4713\/revisions"}],"predecessor-version":[{"id":5537,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4713\/revisions\/5537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media\/5005"}],"wp:attachment":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media?parent=4713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/categories?post=4713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/tags?post=4713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}