{"id":4715,"date":"2026-01-13T12:36:46","date_gmt":"2026-01-13T11:36:46","guid":{"rendered":"https:\/\/turomas.com\/blog\/turomas-mexico-grupo-turomas-inaugura-nueva-delegacion-en-ciudad-de-mexico\/"},"modified":"2026-03-23T12:18:39","modified_gmt":"2026-03-23T11:18:39","slug":"turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico","status":"publish","type":"post","link":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/","title":{"rendered":"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico"},"content":{"rendered":"<h2>A TUROMAS, l\u00edder mundial em solu\u00e7\u00f5es de armazenamento, carga e corte de vidro, abre uma nova delega\u00e7\u00e3o no M\u00e9xico. Esta inaugura\u00e7\u00e3o marca um marco importante na expans\u00e3o da empresa no mercado latino-americano, refor\u00e7ando o seu compromisso com o servi\u00e7o e a proximidade junto dos seus clientes mexicanos.<\/h2>\n<p>A nova delega\u00e7\u00e3o, estrategicamente localizada na Cidade do M\u00e9xico, permitir\u00e1 ao Grupo TUROMAS oferecer um servi\u00e7o mais \u00e1gil e personalizado aos seus clientes na regi\u00e3o, garantindo uma resposta r\u00e1pida e eficiente \u00e0s necessidades do mercado local. Al\u00e9m disso, este novo centro servir\u00e1 como ponto-chave para a distribui\u00e7\u00e3o dos seus produtos, tanto da TUROMAS como da <a href=\"https:\/\/distecglass.com\/\" target=\"_blank\" rel=\"noopener\">Distecglass<\/a>, bem como para a presta\u00e7\u00e3o de servi\u00e7os t\u00e9cnicos e de manuten\u00e7\u00e3o.<\/p>\n<p>A TUROMAS M\u00c9XICO disp\u00f5e de uma ampla disponibilidade de stock, tanto em pe\u00e7as sobresselentes e consum\u00edveis da TUROMAS como em produtos da Distecglass, uma das empresas do grupo especializada na venda de insumos para fachada e vidro duplo. Al\u00e9m disso, a TUROMAS M\u00e9xico conta com uma equipa de 5 profissionais qualificados e com um profundo conhecimento t\u00e9cnico da nossa gama de produtos, que ser\u00e1 respons\u00e1vel por prestar apoio comercial e t\u00e9cnico com a rapidez que os nossos clientes exigem.<\/p>\n<p>Os novos escrit\u00f3rios e o armaz\u00e9m de pe\u00e7as sobresselentes e consum\u00edveis da TUROMAS M\u00e9xico est\u00e3o localizados na Col. Agr\u00edcola Oriental, Iztacalco CP 08500 CDMX, M\u00e9xico. O hor\u00e1rio de funcionamento \u00e9 de segunda a sexta-feira, das 09:00 \u00e0s 13:30 e das 14:00 \u00e0s 17:30. Para mais informa\u00e7\u00f5es, os interessados podem contactar atrav\u00e9s do telefone +52 56 1991 6987 ou do endere\u00e7o de correio eletr\u00f3nico <a href=\"mailto:info@turomas.mx\">info@turomas.mx<\/a><\/p>\n<p>Turomas desembarcou no M\u00e9xico pela primeira vez em novembro de 2012 e rapidamente se expandiu por todo o pa\u00eds, entrando nos principais transformadores de vidro do M\u00e9xico em toda a rep\u00fablica.<br \/>\nGrande parte do sucesso que tivemos \u00e0 chegada deveu-se ao momento econ\u00f3mico que o pa\u00eds atravessava, ao auge da constru\u00e7\u00e3o e \u00e0 procura, por parte dos nossos clientes, de um fornecedor que oferecesse um bom produto, a um pre\u00e7o justo e com um servi\u00e7o pr\u00f3ximo e eficiente. Requisitos b\u00e1sicos e, ao mesmo tempo, inexistentes no M\u00e9xico daquela \u00e9poca.<br \/>\nCreio que a proximidade da Turomas enquanto empresa familiar, a especializa\u00e7\u00e3o no corte de vidro e, consequentemente, a fiabilidade dos seus produtos, bem como o servi\u00e7o pr\u00f3ximo e eficaz que sempre nos caracterizou, foram os principais fatores para termos tido uma aceita\u00e7\u00e3o t\u00e3o r\u00e1pida e bem-sucedida.<br \/>\nComo consequ\u00eancia desse acolhimento e dos bons resultados alcan\u00e7ados ao longo destes doze anos, al\u00e9m dos la\u00e7os pessoais que estabelecemos com os nossos clientes \u2014 muitos dos quais temos o privil\u00e9gio de chamar amigos \u2014, sentimos o impulso necess\u00e1rio para alcan\u00e7ar um dos marcos mais importantes da hist\u00f3ria da Turomas nos seus quarenta anos: tornar a Turomas M\u00e9xico uma realidade.<br \/>\n<cite>\u00c1lvaro Tom\u00e1sCEO &#8211; Diretor-Geral do Grupo TUROMAS<\/cite>\t\t\t<\/p>\n<p>A cerim\u00f3nia de inaugura\u00e7\u00e3o, que se realizar\u00e1 no pr\u00f3ximo m\u00eas de julho, aproveitando a feira Glasstech M\u00e9xico, contar\u00e1 com a presen\u00e7a de destacados representantes da ind\u00fastria do vidro, bem como de clientes e parceiros estrat\u00e9gicos do Grupo TUROMAS.<\/p>\n<p>Durante o evento, ser\u00e1 feita uma apresenta\u00e7\u00e3o da delega\u00e7\u00e3o e dos seus servi\u00e7os, al\u00e9m de serem apresentados os mais recentes avan\u00e7os tecnol\u00f3gicos desenvolvidos pela empresa, oferecendo aos participantes a oportunidade de conhecer em primeira m\u00e3o as solu\u00e7\u00f5es que a TUROMAS M\u00c9XICO pode oferecer ao mercado.<\/p>\n<p>Com mais de 40 anos de experi\u00eancia, o Grupo TUROMAS consolidou a sua posi\u00e7\u00e3o como l\u00edder do setor gra\u00e7as ao seu compromisso com a qualidade, a inova\u00e7\u00e3o e o apoio ao cliente. A abertura da delega\u00e7\u00e3o na Cidade do M\u00e9xico n\u00e3o representa apenas uma expans\u00e3o geogr\u00e1fica, mas tamb\u00e9m um refor\u00e7o das rela\u00e7\u00f5es com os clientes latino-americanos e um impulso ao crescimento da empresa na regi\u00e3o.<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre a delega\u00e7\u00e3o da TUROMAS M\u00c9XICO, por favor contacte a nossa equipa de imprensa atrav\u00e9s de <a href=\"mailto:marketing@turomas.com\">marketing@turomas.com<\/a> ou <a href=\"mailto:info@turomas.mx\">info@turomas.mx<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TUROMAS abre una nueva delegaci\u00f3n en M\u00e9xico. Esta apertura marca un hito importante en la expansi\u00f3n de la compa\u00f1\u00eda en el mercado latinoamericano, reforzando su compromiso con el servicio y la cercan\u00eda de sus clientes mexicanos.<\/p>\n","protected":false},"author":1,"featured_media":5009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3,4],"tags":[],"class_list":["post-4715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turomas-in-the-world","category-turomas-news","category-turomas-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico | Turomas PT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico | Turomas PT\" \/>\n<meta property=\"og:description\" content=\"TUROMAS abre una nueva delegaci\u00f3n en M\u00e9xico. Esta apertura marca un hito importante en la expansi\u00f3n de la compa\u00f1\u00eda en el mercado latinoamericano, reforzando su compromiso con el servicio y la cercan\u00eda de sus clientes mexicanos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Turomas PT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turomas.machinery\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T11:36:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T11:18:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/1-1-768x768-1-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"turomas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@turomas\" \/>\n<meta name=\"twitter:site\" content=\"@turomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"turomas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/\"},\"author\":{\"name\":\"turomas_admin\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"headline\":\"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico\",\"datePublished\":\"2026-01-13T11:36:46+00:00\",\"dateModified\":\"2026-03-23T11:18:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/\"},\"wordCount\":737,\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1-1-768x768-1-3.jpg\",\"articleSection\":[\"TUROMAS IN THE WORLD\",\"TUROMAS NEWS\",\"TUROMAS TECHNOLOGY\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/\",\"name\":\"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico | Turomas PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1-1-768x768-1-3.jpg\",\"datePublished\":\"2026-01-13T11:36:46+00:00\",\"dateModified\":\"2026-03-23T11:18:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1-1-768x768-1-3.jpg\",\"contentUrl\":\"https:\\\/\\\/turomas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1-1-768x768-1-3.jpg\",\"width\":768,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/blog\\\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/turomas.com\\\/pt\\\/\",\"name\":\"Turomas PT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turomas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/turomas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a1044b4455871da8a310655103de9315\",\"name\":\"turomas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g\",\"caption\":\"turomas_admin\"},\"sameAs\":[\"https:\\\/\\\/turomas.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico | Turomas PT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/","og_locale":"pt_PT","og_type":"article","og_title":"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico | Turomas PT","og_description":"TUROMAS abre una nueva delegaci\u00f3n en M\u00e9xico. Esta apertura marca un hito importante en la expansi\u00f3n de la compa\u00f1\u00eda en el mercado latinoamericano, reforzando su compromiso con el servicio y la cercan\u00eda de sus clientes mexicanos.","og_url":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/","og_site_name":"Turomas PT","article_publisher":"https:\/\/www.facebook.com\/turomas.machinery","article_published_time":"2026-01-13T11:36:46+00:00","article_modified_time":"2026-03-23T11:18:39+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/1-1-768x768-1-3.jpg","type":"image\/jpeg"}],"author":"turomas_admin","twitter_card":"summary_large_image","twitter_creator":"@turomas","twitter_site":"@turomas","twitter_misc":{"Escrito por":"turomas_admin","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/#article","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/"},"author":{"name":"turomas_admin","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"headline":"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico","datePublished":"2026-01-13T11:36:46+00:00","dateModified":"2026-03-23T11:18:39+00:00","mainEntityOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/"},"wordCount":737,"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/1-1-768x768-1-3.jpg","articleSection":["TUROMAS IN THE WORLD","TUROMAS NEWS","TUROMAS TECHNOLOGY"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/","url":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/","name":"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico | Turomas PT","isPartOf":{"@id":"https:\/\/turomas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/#primaryimage"},"image":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/1-1-768x768-1-3.jpg","datePublished":"2026-01-13T11:36:46+00:00","dateModified":"2026-03-23T11:18:39+00:00","author":{"@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315"},"breadcrumb":{"@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/#primaryimage","url":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/1-1-768x768-1-3.jpg","contentUrl":"https:\/\/turomas.com\/pt\/wp-content\/uploads\/2026\/01\/1-1-768x768-1-3.jpg","width":768,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/turomas.com\/pt\/blog\/turomas-mexico-grupo-turomas-inaugura-nova-delegacao-cidade-do-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turomas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"TUROMAS M\u00c9XICO: o Grupo TUROMAS inaugura nova delega\u00e7\u00e3o na Cidade do M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/turomas.com\/pt\/#website","url":"https:\/\/turomas.com\/pt\/","name":"Turomas PT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turomas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/turomas.com\/pt\/#\/schema\/person\/a1044b4455871da8a310655103de9315","name":"turomas_admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299019ab804c1efaaf8b85257cf8935995918ac9344cdebee523cba8d7390472?s=96&d=mm&r=g","caption":"turomas_admin"},"sameAs":["https:\/\/turomas.com"]}]}},"_links":{"self":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/comments?post=4715"}],"version-history":[{"count":1,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4715\/revisions"}],"predecessor-version":[{"id":5558,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/posts\/4715\/revisions\/5558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media\/5009"}],"wp:attachment":[{"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/media?parent=4715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/categories?post=4715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turomas.com\/pt\/wp-json\/wp\/v2\/tags?post=4715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}